{"id":3847,"date":"2019-08-20T10:16:30","date_gmt":"2019-08-20T14:16:30","guid":{"rendered":"http:\/\/theesa.ca\/fr\/?p=3847"},"modified":"2019-08-20T10:16:30","modified_gmt":"2019-08-20T14:16:30","slug":"canadianscreenawards2020-2","status":"publish","type":"post","link":"https:\/\/theesa.ca\/fr\/canadianscreenawards2020-2\/","title":{"rendered":"Prix \u00c9crans canadiens 2020 : Nouvelles cat\u00e9gories pour les Jeux Vid\u00e9o \u2013 Date limite de soumission est le 1er septembre 2019"},"content":{"rendered":"<h3 style=\"text-align: center;\">Meilleure narrative de jeu vid\u00e9o et Meilleure narrative de jeu vid\u00e9o pour enfants<\/h3>\n<p style=\"text-align: center;\">L\u2019Acad\u00e9mie Canadienne du Cin\u00e9ma et de la T\u00e9l\u00e9vision a ouvert les inscriptions en ligne pour les Prix \u00c9crans canadiens 2020. Nous sommes ravis d\u2019annoncer que cette ann\u00e9e les Prix \u00c9crans canadiens comprennent deux cat\u00e9gories pour les jeux vid\u00e9o\u00a0: Best Video Game Narrative (Meilleure narrative de jeu vid\u00e9o) et Best Children\u2019s Video Game Narrative (Meilleure narrative de jeu vid\u00e9o pour enfants).<\/p>\n<p style=\"text-align: center;\">Apprendre plus sur ces nouvelles cat\u00e9gories et soumettre votre jeu avant le 1er septembre 2019 au <a href=\"https:\/\/www.academy.ca\/awards\/\">Prix \u00c9crans canadiens 2020<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meilleure narrative de jeu vid\u00e9o et Meilleure narrative de jeu<\/p>\n","protected":false},"author":1,"featured_media":3816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1],"tags":[],"class_list":["post-3847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/posts\/3847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/comments?post=3847"}],"version-history":[{"count":0,"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/posts\/3847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theesa.ca\/fr\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/media?parent=3847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/categories?post=3847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theesa.ca\/fr\/wp-json\/wp\/v2\/tags?post=3847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}